{"id":13188,"date":"2014-07-09T18:38:53","date_gmt":"2014-07-09T16:38:53","guid":{"rendered":"https:\/\/www.sombrasblancasdesign.com\/shop\/e-commerce-para-wordpress\/"},"modified":"2014-07-09T18:38:53","modified_gmt":"2014-07-09T16:38:53","slug":"e-commerce-para-wordpress","status":"publish","type":"product","link":"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/","title":{"rendered":"E-Commerce para WordPress"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Si est\u00e1s pensando en comprar mi servicio de dise\u00f1o de p\u00e1gina web en WordPress y quieres que incluya una tienda online, a\u00f1ade este producto a tu tienda.<\/p>\n<p>Usar\u00e9 el plugin WooCommerce para crear una p\u00e1gina de e-commerce totalmente integrada en tu web y acorde con tus necesidades. Tambi\u00e9n subir\u00e9 tus 10 primeros productos. <\/p>\n","protected":false},"featured_media":12294,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[3375],"product_tag":[],"class_list":["post-13188","product","type-product","status-publish","has-post-thumbnail","product_cat-diseno-web","first","instock","virtual","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E-Commerce para WordPress - Sombras Blancas Art &amp; Design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E-Commerce para WordPress - Sombras Blancas Art &amp; Design\" \/>\n<meta property=\"og:description\" content=\"Si est\u00e1s pensando en comprar mi servicio de dise\u00f1o de p\u00e1gina web en WordPress y quieres que incluya una tienda online, a\u00f1ade este producto a tu tienda. Usar\u00e9 el plugin WooCommerce para crear una p\u00e1gina de e-commerce totalmente integrada en tu web y acorde con tus necesidades. Tambi\u00e9n subir\u00e9 tus 10 primeros productos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Sombras Blancas Art &amp; Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sombrasblancasart\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sombrasblancasdesign.com\/wp-content\/uploads\/2014\/07\/wordpress-shop.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/es\\\/shop\\\/e-commerce-para-wordpress\\\/\",\"url\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/es\\\/shop\\\/e-commerce-para-wordpress\\\/\",\"name\":\"E-Commerce para WordPress - Sombras Blancas Art &amp; Design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/es\\\/shop\\\/e-commerce-para-wordpress\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/es\\\/shop\\\/e-commerce-para-wordpress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/wordpress-shop.jpg\",\"datePublished\":\"2014-07-09T16:38:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/es\\\/shop\\\/e-commerce-para-wordpress\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/es\\\/shop\\\/e-commerce-para-wordpress\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/es\\\/shop\\\/e-commerce-para-wordpress\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/wordpress-shop.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/wordpress-shop.jpg\",\"width\":650,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/es\\\/shop\\\/e-commerce-para-wordpress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/shop-archive\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"E-Commerce para WordPress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/#website\",\"url\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/\",\"name\":\"Sombras Blancas Art & Design\",\"description\":\"Professional web and brand design for solo service providers and small businesses\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/#organization\",\"name\":\"Sombras Blancas Art & Design\",\"url\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sombrasblancasdesign.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/brand-design-for-small-businesses-3.jpg\",\"contentUrl\":\"http:\\\/\\\/www.sombrasblancasdesign.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/brand-design-for-small-businesses-3.jpg\",\"width\":1000,\"height\":732,\"caption\":\"Sombras Blancas Art & Design\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sombrasblancasdesign.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sombrasblancasart\",\"https:\\\/\\\/x.com\\\/sombrasblancas\",\"https:\\\/\\\/www.instagram.com\\\/sombrasblancasdesign\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E-Commerce para WordPress - Sombras Blancas Art &amp; Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/","og_locale":"es_ES","og_type":"article","og_title":"E-Commerce para WordPress - Sombras Blancas Art &amp; Design","og_description":"Si est\u00e1s pensando en comprar mi servicio de dise\u00f1o de p\u00e1gina web en WordPress y quieres que incluya una tienda online, a\u00f1ade este producto a tu tienda. Usar\u00e9 el plugin WooCommerce para crear una p\u00e1gina de e-commerce totalmente integrada en tu web y acorde con tus necesidades. Tambi\u00e9n subir\u00e9 tus 10 primeros productos.","og_url":"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/","og_site_name":"Sombras Blancas Art &amp; Design","article_publisher":"https:\/\/www.facebook.com\/sombrasblancasart","og_image":[{"width":650,"height":650,"url":"https:\/\/www.sombrasblancasdesign.com\/wp-content\/uploads\/2014\/07\/wordpress-shop.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/","url":"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/","name":"E-Commerce para WordPress - Sombras Blancas Art &amp; Design","isPartOf":{"@id":"https:\/\/www.sombrasblancasdesign.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/#primaryimage"},"image":{"@id":"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sombrasblancasdesign.com\/wp-content\/uploads\/2014\/07\/wordpress-shop.jpg","datePublished":"2014-07-09T16:38:53+00:00","breadcrumb":{"@id":"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/#primaryimage","url":"https:\/\/www.sombrasblancasdesign.com\/wp-content\/uploads\/2014\/07\/wordpress-shop.jpg","contentUrl":"https:\/\/www.sombrasblancasdesign.com\/wp-content\/uploads\/2014\/07\/wordpress-shop.jpg","width":650,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/www.sombrasblancasdesign.com\/es\/shop\/e-commerce-para-wordpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sombrasblancasdesign.com\/es\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.sombrasblancasdesign.com\/shop-archive\/"},{"@type":"ListItem","position":3,"name":"E-Commerce para WordPress"}]},{"@type":"WebSite","@id":"https:\/\/www.sombrasblancasdesign.com\/#website","url":"https:\/\/www.sombrasblancasdesign.com\/","name":"Sombras Blancas Art & Design","description":"Professional web and brand design for solo service providers and small businesses","publisher":{"@id":"https:\/\/www.sombrasblancasdesign.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sombrasblancasdesign.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sombrasblancasdesign.com\/#organization","name":"Sombras Blancas Art & Design","url":"https:\/\/www.sombrasblancasdesign.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sombrasblancasdesign.com\/#\/schema\/logo\/image\/","url":"http:\/\/www.sombrasblancasdesign.com\/wp-content\/uploads\/2022\/06\/brand-design-for-small-businesses-3.jpg","contentUrl":"http:\/\/www.sombrasblancasdesign.com\/wp-content\/uploads\/2022\/06\/brand-design-for-small-businesses-3.jpg","width":1000,"height":732,"caption":"Sombras Blancas Art & Design"},"image":{"@id":"https:\/\/www.sombrasblancasdesign.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sombrasblancasart","https:\/\/x.com\/sombrasblancas","https:\/\/www.instagram.com\/sombrasblancasdesign\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.sombrasblancasdesign.com\/es\/wp-json\/wp\/v2\/product\/13188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sombrasblancasdesign.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sombrasblancasdesign.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sombrasblancasdesign.com\/es\/wp-json\/wp\/v2\/comments?post=13188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sombrasblancasdesign.com\/es\/wp-json\/wp\/v2\/media\/12294"}],"wp:attachment":[{"href":"https:\/\/www.sombrasblancasdesign.com\/es\/wp-json\/wp\/v2\/media?parent=13188"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sombrasblancasdesign.com\/es\/wp-json\/wp\/v2\/product_brand?post=13188"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sombrasblancasdesign.com\/es\/wp-json\/wp\/v2\/product_cat?post=13188"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sombrasblancasdesign.com\/es\/wp-json\/wp\/v2\/product_tag?post=13188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}